{"id":35203,"date":"2025-03-11T17:16:29","date_gmt":"2025-03-11T16:16:29","guid":{"rendered":"https:\/\/bs-battery.com\/condiciones-generales\/"},"modified":"2026-03-30T08:53:21","modified_gmt":"2026-03-30T06:53:21","slug":"condiciones-generales","status":"publish","type":"page","link":"https:\/\/bs-battery.com\/es\/condiciones-generales\/","title":{"rendered":"CONDICIONES GENERALES"},"content":{"rendered":"<section class=\"l-section wpb_row us_custom_c558bd28 height_small width_full with_img with_shape\"><div class=\"l-section-img\" style=\"background-image: url(https:\/\/bs-battery.com\/wp-content\/uploads\/2021\/09\/lithium.jpg);background-position: center right;background-repeat: no-repeat;\" data-img-width=\"1500\" data-img-height=\"481\"><\/div><div class=\"l-section-overlay\" style=\"background:rgba(26,26,26,0.67)\"><\/div><div class=\"l-section-shape type_tilt pos_bottom hor_flip\" style=\"height:10vh;color:#ffffff\"><svg xmlns=\"http:\/\/www.w3.org\/2000\/svg\" viewBox=\"0 0 64 8\" preserveAspectRatio=\"none\" width=\"100%\" height=\"100%\">\r\n\t<path fill=\"currentColor\" d=\"M64 7.9 L64 10 L0 10 L0 0 Z\"\/>\r\n<\/svg><\/div><div class=\"l-section-h i-cf\"><div class=\"g-cols via_flex valign_top type_default\"><div class=\"vc_col-sm-12 wpb_column vc_column_container \"><div class=\"vc_column-inner us_custom_4ef5d869 us_animate_this\"><div class=\"wpb_wrapper\"><h1 class=\"w-post-elm post_title us_custom_6df4bc3a align_left entry-title color_link_inherit has_text_color\">CONDICIONES GENERALES<\/h1><ol class=\"g-breadcrumbs us_custom_75c73c39 separator_icon align_left has_text_color\" itemscope itemtype=\"http:\/\/schema.org\/BreadcrumbList\"><li class=\"g-breadcrumbs-item\" itemscope itemprop=\"itemListElement\" itemtype=\"http:\/\/schema.org\/ListItem\"><a itemprop=\"item\" href=\"https:\/\/bs-battery.com\/es\/\"><span itemprop=\"name\">HOME<\/span><\/a><meta itemprop=\"position\" content=\"1\"\/><\/li><li class=\"g-breadcrumbs-separator\"><i class=\"far fa-angle-right\"><\/i><\/li><li class=\"g-breadcrumbs-item\">P\u00e1ginas<\/li><\/ol><div class=\"w-separator size_small\"><\/div><div class=\"w-separator size_huge\"><\/div><\/div><\/div><\/div><\/div><\/div><\/section><section class=\"l-section wpb_row height_small\"><div class=\"l-section-h i-cf\"><div class=\"g-cols via_flex valign_top type_default\"><div class=\"vc_col-sm-12 wpb_column vc_column_container\"><div class=\"vc_column-inner\"><div class=\"wpb_wrapper\"><div class=\"w-tabs layout_hor style_default switch_click has_scrolling\" style=\"--sections-title-size:1em\"><div class=\"w-tabs-list items_3\"><div class=\"w-tabs-list-h\"><a class=\"w-tabs-item active\" aria-controls=\"content-e000\" href=\"javascript:void(0);\"><span class=\"w-tabs-item-title\">AVISO LEGAL<\/span><\/a><a class=\"w-tabs-item\" aria-controls=\"content-gb19\" href=\"javascript:void(0);\"><span class=\"w-tabs-item-title\">POL\u00cdTICA DE PRIVACIDAD<\/span><\/a><a class=\"w-tabs-item\" aria-controls=\"content-ce05\" href=\"javascript:void(0);\"><span class=\"w-tabs-item-title\">CONDICIONES DE USO<\/span><\/a><\/div><\/div><div class=\"w-tabs-sections titles-align_none icon_chevron cpos_right\"><div class=\"w-tabs-section active\" id=\"e000\"><button aria-controls=\"content-e000\" class=\"w-tabs-section-header active\"><div class=\"w-tabs-section-title\">AVISO LEGAL<\/div><div class=\"w-tabs-section-control\"><\/div><\/button><div class=\"w-tabs-section-content\" id=\"content-e000\" aria-expanded=\"true\"><div class=\"w-tabs-section-content-h i-cf\"><div class=\"wpb_text_column\"><div class=\"wpb_wrapper\"><p>Welcome to the website <u>bs-battery.com<\/u>, a website operated by COFINAS Sas, a company incorporated the laws of France with the SIRET registration number 30593368100069 and registered at the address: 30 RUE PASTEUR, 92150 SURESNES, FRANCE.<\/p>\n<h4><span style=\"color: #cd1719;\">ADDITIONAL INFORMATION ABOUT COFINAS Sas:<\/span><\/h4>\n<ul>\n<li>N\u00famero de registro de IVA: FR 53 305 933 681<\/li>\n<li>Director de la publicaci\u00f3n: Menduni, Romain &#8211; <a href=\"mailto:rmenduni@cofinas.com\">rmenduni@cofinas.com<\/a><\/li>\n<li>Anfitri\u00f3n del sitio web:<\/li>\n<\/ul>\n<p>Capital social de OVH SAS: 10 174 560 \u20ac.<\/p>\n<p>RCS Lille M\u00e9tropole 424 761 419 00045<br \/>\nN\u00famero de IVA : FR 22 424 761 419<br \/>\n2 rue Kellermann<br \/>\n59100 Roubaix, Francia<\/p>\n<p><strong><em>MERCASAFE 2024<\/em><\/strong><em>\u00a9<\/em><em> &#8211;<\/em><em>MS 1001-179048<\/em><\/p>\n<\/div><\/div><\/div><\/div><\/div><div class=\"w-tabs-section\" id=\"gb19\"><button aria-controls=\"content-gb19\" class=\"w-tabs-section-header\"><div class=\"w-tabs-section-title\">POL\u00cdTICA DE PRIVACIDAD<\/div><div class=\"w-tabs-section-control\"><\/div><\/button><div class=\"w-tabs-section-content\" id=\"content-gb19\" aria-expanded=\"false\"><div class=\"w-tabs-section-content-h i-cf\"><div class=\"wpb_text_column\"><div class=\"wpb_wrapper\"><style type=\"text\/css\">\ntd { border: 1px solid}<\/style>\n<p><u>bs-battery.com<\/u>, is a website owned by COFINAS Sas, a company incorporated the laws of France with the registration number 30593368100069 and registered at the address: 30 RUE PASTEUR, 92150 SURESNES, FRANCE (hereinafter referred to as the \u00ab<strong>Data Controller<\/strong>\u00ab). <u>bs-battery.com<\/u> is very concerned about the confidentiality of your personal data as Users who visit and browse our Website.<\/p>\n<p>Por ello, nosotros, <u>bs-battery.com<\/u> (en adelante, el<strong>\u00abSitio Web<\/strong>\u00ab), nos esforzamos por respetar tus derechos, tal y como se establece en el Reglamento General de Protecci\u00f3n de Datos 2017\/679 (RGPD) y en las Directivas sobre privacidad electr\u00f3nica del Parlamento Europeo y del Consejo.<\/p>\n<h4><span style=\"color: #cd1719;\">1. DEFINICIONES<\/span><\/h4>\n<ul>\n<li>1.<strong>\u00abDatos personales<\/strong>\u00bb o \u00abdatos de car\u00e1cter personal\u00bb: cualquier informaci\u00f3n relativa a una persona f\u00edsica identificada o identificable (en lo sucesivo, \u00abinteresado\u00bb); se considera \u00abpersona f\u00edsica identificable\u00bb a toda persona f\u00edsica que pueda ser identificada, directa o indirectamente, en particular mediante un identificador, como un nombre, un n\u00famero de identificaci\u00f3n, datos de localizaci\u00f3n, un identificador en l\u00ednea, o uno o varios elementos propios de su identidad f\u00edsica, fisiol\u00f3gica, gen\u00e9tica, ps\u00edquica, econ\u00f3mica, cultural o social;<\/li>\n<li>2. \u00ab<strong>tratamiento<\/strong>\u00ab: cualquier operaci\u00f3n o conjunto de operaciones, efectuadas o no mediante procedimientos automatizados, que se realicen con datos personales o conjuntos de datos personales, como la recogida, registro, organizaci\u00f3n, estructuraci\u00f3n, conservaci\u00f3n, elaboraci\u00f3n o modificaci\u00f3n, extracci\u00f3n, consulta, utilizaci\u00f3n, comunicaci\u00f3n por transmisi\u00f3n, difusi\u00f3n o cualquier otra forma de habilitaci\u00f3n de acceso, cotejo o interconexi\u00f3n, limitaci\u00f3n, supresi\u00f3n o destrucci\u00f3n;<\/li>\n<li>3.<strong>\u00abresponsable del<\/strong> tratamiento\u00bb: la persona f\u00edsica o jur\u00eddica, autoridad p\u00fablica, servicio u otro organismo que, solo o conjuntamente con otros, determine los fines y los medios del tratamiento; cuando los fines y los medios de dicho tratamiento est\u00e9n determinados por el Derecho de la Uni\u00f3n o de un Estado miembro, el responsable del tratamiento podr\u00e1 ser designado o los criterios espec\u00edficos para dicha designaci\u00f3n podr\u00e1n ser establecidos por el Derecho de la Uni\u00f3n o de un Estado miembro.<\/li>\n<li>4.<strong>\u00abencargado del tratamiento<\/strong>\u00ab: la persona f\u00edsica o jur\u00eddica, autoridad p\u00fablica, agencia u otro organismo que trate datos personales por cuenta del responsable del tratamiento<\/li>\n<li>5. \u00ab<strong>destinatario<\/strong>\u00ab: la persona f\u00edsica o jur\u00eddica, autoridad p\u00fablica, agencia o cualquier otro organismo al que se comuniquen datos de car\u00e1cter personal, ya sea un tercero o no. No obstante, no se considerar\u00e1n destinatarias las autoridades p\u00fablicas 4.5.2016 L 119\/33 Diario Oficial de la Uni\u00f3n Europea ES que puedan recibir la comunicaci\u00f3n de datos personales en el marco de una misi\u00f3n de investigaci\u00f3n concreta de conformidad con el Derecho de la Uni\u00f3n o de un Estado miembro; el tratamiento de dichos datos por las autoridades p\u00fablicas en cuesti\u00f3n se ajustar\u00e1 a las normas de protecci\u00f3n de datos aplicables en funci\u00f3n de los fines del tratamiento;<\/li>\n<li>6.<strong>\u00abconsentimiento<\/strong>\u00bb del interesado: toda manifestaci\u00f3n de voluntad, libre, espec\u00edfica, informada e inequ\u00edvoca, por la que el interesado consiente, mediante una declaraci\u00f3n o un acto positivo claro, el tratamiento de datos personales que le conciernen<\/li>\n<li>7. \u00ab<strong>violaci\u00f3n de datos personales<\/strong>\u00ab: una violaci\u00f3n de la seguridad que provoque la destrucci\u00f3n, accidental o il\u00edcita, la p\u00e9rdida, la alteraci\u00f3n, la difusi\u00f3n no autorizada o el acceso a datos personales transmitidos, almacenados o tratados de otro modo.<\/li>\n<li>8.<strong>\u00abcookie<\/strong>\u00ab, una cookie es un archivo de texto que se almacena autom\u00e1ticamente en el navegador de cualquier Usuario cuando visita un sitio web. Este archivo de texto puede contener datos personales y\/o informaci\u00f3n relativa a la navegaci\u00f3n del Usuario.<\/li>\n<\/ul>\n<h4><span style=\"color: #cd1719;\">2. PROP\u00d3SITO<\/span><\/h4>\n<p>La presente Pol\u00edtica de Privacidad y Cookies (en adelante, la<strong>\u00abPol\u00edtica<\/strong>\u00ab) tiene por objeto definir las modalidades de recogida, almacenamiento y tratamiento de los datos personales (en adelante, los<strong>\u00abDatos Personales<\/strong>\u00ab) de toda persona f\u00edsica (en adelante, el<strong>\u00abUsuario<\/strong>\u00ab) que, en el marco de una actividad estrictamente personal o dom\u00e9stica, utilice o simplemente navegue por este Sitio Web.<\/p>\n<p>El Responsable del Tratamiento asegura al Usuario que implementa todos los medios necesarios para garantizar el cumplimiento de las disposiciones del Reglamento General de Protecci\u00f3n de Datos 2017\/679 del Parlamento Europeo y del Consejo, de 14 de abril de 2016, asegurando el cumplimiento de los plazos de conservaci\u00f3n, la necesidad de recabar los citados datos personales y la confidencialidad de los datos personales recabados (en adelante, el \u00abReglamento\u00bb o el<strong>\u00abGDPR<\/strong>\u00ab).<\/p>\n<h4><span style=\"color: #cd1719;\">3. CONSENTIMIENTO DEL USUARIO<\/span><\/h4>\n<p>Esta Pol\u00edtica debe ser le\u00edda y aceptada por cualquier Usuario que visite el Sitio Web. Al hacer clic en la casilla<strong>\u00able\u00edda y aceptada<\/strong>\u00bb que hace referencia a esta Pol\u00edtica en el momento de su llegada al Sitio Web y\/o en el momento de la recogida de cualquier dato personal del Usuario, el Usuario reconoce haberla le\u00eddo y da su consentimiento libre, informado e inequ\u00edvoco al tratamiento de sus datos personales.<\/p>\n<p>El Usuario puede, en cualquier momento y sin justificaci\u00f3n ni perjuicio, retirar su consentimiento a esta Pol\u00edtica. El Usuario podr\u00e1 ejercer su derecho a retirar el consentimiento a esta Pol\u00edtica notific\u00e1ndolo al Responsable del Tratamiento a la siguiente direcci\u00f3n de correo electr\u00f3nico: .<\/p>\n<p>Esta retirada del consentimiento surtir\u00e1 efecto en el momento en que el Responsable del Tratamiento reciba la notificaci\u00f3n de la retirada del consentimiento del Usuario.<\/p>\n<h4><span style=\"color: #cd1719;\">4. DATOS RECOGIDOS<\/span><\/h4>\n<p>En el contexto de la visita y uso del Sitio Web, ciertos Datos Personales de los Usuarios pueden ser recogidos por <u>bs-battery.com<\/u>, en su calidad de Responsable del Tratamiento o por uno o varios subcontratistas que act\u00faen en nombre y por cuenta del Responsable del Tratamiento.<\/p>\n<p><strong> a. <\/strong><strong>Medios de recogida<\/strong><\/p>\n<p>Los datos personales del Usuario se recogen por los siguientes medios:<\/p>\n<ul>\n<li><strong>Cuando el Usuario las comunique bien <\/strong>rellenando el formulario de contacto del Sitio Web.<\/li>\n<li><strong>Mediante la recogida automatizada<\/strong><\/li>\n<\/ul>\n<p>Durante la navegaci\u00f3n del Usuario por el Sitio Web, el Responsable del Tratamiento registra autom\u00e1ticamente cierta informaci\u00f3n relativa a las preferencias del Usuario y al uso del Sitio Web. Se utilizan cookies durante la navegaci\u00f3n del Usuario por el Sitio Web para recopilar esta informaci\u00f3n autom\u00e1ticamente.<\/p>\n<p><strong>b. <\/strong><strong>Tipo de datos personales recogidos<\/strong><\/p>\n<p>Los datos personales que pueden recogerse son:<\/p>\n<ul>\n<li>La direcci\u00f3n de correo electr\u00f3nico del Usuario;<\/li>\n<li>El apellido y el nombre del Usuario;<\/li>\n<li>Cualquier informaci\u00f3n proporcionada por el Usuario en el formulario de Contacto o cualquier comunicaci\u00f3n enviada al Responsable del Tratamiento;<\/li>\n<li>Preferencias de navegaci\u00f3n e informaci\u00f3n sobre el dispositivo del Usuario utilizado para navegar por el Sitio Web<strong>.c. <\/strong><strong>Destinatarios de los Datos Personales<\/strong><\/li>\n<\/ul>\n<p>Los destinatarios de los datos personales son:<\/p>\n<table width=\"554\">\n<thead>\n<tr>\n<td width=\"172\"><strong>Finalidad del intercambio de datos<\/strong><\/td>\n<td width=\"382\"><strong>Destinatario<\/strong><\/td>\n<\/tr>\n<tr>\n<td width=\"172\">Alojamiento web\/dominio<\/td>\n<td width=\"382\">OVH SAS, N\u00famero de empresa: 424 761 419 00045, 2 rue Kellermann 59100 Roubaix, Francia<\/td>\n<\/tr>\n<\/thead>\n<\/table>\n<p>&nbsp;<\/p>\n<h4><span style=\"color: #cd1719;\">5. TRATAMIENTO DE DATOS<\/span><\/h4>\n<p><strong>a. <\/strong><strong>Base jur\u00eddica del tratamiento<\/strong><\/p>\n<p>El tratamiento de los datos personales de los Usuarios a trav\u00e9s del Sitio Web debe estar necesariamente justificado por una de las condiciones establecidas en <em>el Art\u00edculo 6(1) del Reglamento<\/em>. De conformidad con el Reglamento, los datos personales de los Usuarios s\u00f3lo se tratar\u00e1n si se cumple una de las siguientes condiciones:<\/p>\n<ul>\n<li>El Usuario ha dado su consentimiento: el Usuario en cuesti\u00f3n ha consentido el tratamiento de sus datos personales para uno o varios fines espec\u00edficos;<\/li>\n<li>La ejecuci\u00f3n del contrato lo requiere: el tratamiento es necesario para la ejecuci\u00f3n de un contrato en el que el Usuario en cuesti\u00f3n es parte o para la ejecuci\u00f3n de medidas precontractuales adoptadas a petici\u00f3n del Usuario;<\/li>\n<li>Lo exige el respeto de la ley: el tratamiento es necesario para el cumplimiento de una obligaci\u00f3n legal a la que est\u00e1 sujeto el responsable del tratamiento;<\/li>\n<li>Un inter\u00e9s leg\u00edtimo lo justifica: el tratamiento es necesario a efectos de los intereses leg\u00edtimos perseguidos por el responsable del tratamiento o por un tercero, salvo que prevalezcan los intereses o los derechos y libertades fundamentales del Usuario afectado, que requieren la protecci\u00f3n de los datos personales, en particular cuando el Usuario afectado es menor de edad.<\/li>\n<\/ul>\n<p><strong>b. <\/strong><strong>Fines del tratamiento y periodo de conservaci\u00f3n de los datos<\/strong><\/p>\n<p>De conformidad con el art\u00edculo 13 del Reglamento, el motivo y la duraci\u00f3n del almacenamiento y el tratamiento de los datos personales deben estar justificados por un fin v\u00e1lido, adem\u00e1s de por una de las bases jur\u00eddicas enumeradas anteriormente.<\/p>\n<table width=\"602\">\n<tbody>\n<tr>\n<td width=\"250\"><strong>Finalidad<\/strong><\/td>\n<td width=\"132\"><strong>Base jur\u00eddica<\/strong><\/td>\n<td width=\"127\"><strong>Duraci\u00f3n<\/strong><\/td>\n<td width=\"93\"><strong>Duraci\u00f3n del archivo<\/strong><\/td>\n<\/tr>\n<tr>\n<td width=\"250\">Comunicaci\u00f3n de marketing y ofertas por parte del Responsable del Tratamiento y respuesta a solicitudes de contacto\/presupuesto<\/td>\n<td width=\"132\">Inter\u00e9s leg\u00edtimo<\/td>\n<td width=\"127\">3 a\u00f1os<\/td>\n<td width=\"93\">NO APLICABLE<\/td>\n<\/tr>\n<tr>\n<td width=\"250\">Prevenci\u00f3n del fraude<\/td>\n<td width=\"132\">Inter\u00e9s leg\u00edtimo<\/td>\n<td width=\"127\">3 a\u00f1os<\/td>\n<td width=\"93\">5 a\u00f1os<\/td>\n<\/tr>\n<tr>\n<td width=\"250\">Analysis of the Site&#8217;s navigation data, creation of site visit statistics, and facilitation of the User&#8217;s navigation<\/td>\n<td width=\"132\">Consent<\/td>\n<td width=\"127\">12 months from the time the cookies are first deposited on the User&#8217;s browser<\/p>\n<p>&nbsp;<\/td>\n<td width=\"93\">N\/A<\/td>\n<\/tr>\n<\/tbody>\n<\/table>\n<p>&nbsp;<\/p>\n<h4><span style=\"color: #cd1719;\">6. MEDIOS DE PROTECCI\u00d3N DE DATOS<\/span><\/h4>\n<p>De conformidad con el art\u00edculo 5 y el art\u00edculo 32 del Reglamento, el Responsable del Tratamiento est\u00e1 obligado a garantizar la seguridad de los datos personales de los Usuarios que almacene y trate.<\/p>\n<p>El Responsable del Tratamiento mantendr\u00e1 un registro con todos los datos personales de los Usuarios recopilados. El Responsable del Tratamiento afirma que aplica todas las medidas de seguridad necesarias para proteger los datos personales de los Usuarios contenidos en este registro y para evitar cualquier violaci\u00f3n de los datos personales de los Usuarios.<\/p>\n<p>Para ello, el Responsable del Tratamiento afirma a los Usuarios que ha realizado un estudio de los riesgos asociados al almacenamiento y tratamiento de los datos personales de los Usuarios con el fin de aplicar las medidas de seguridad adecuadas que se indican a continuaci\u00f3n:<\/p>\n<ul>\n<li>Permitiendo la seudonimizaci\u00f3n y encriptaci\u00f3n de los datos personales del Usuario;<\/li>\n<li>Implementar medios para garantizar en todo momento la confidencialidad, integridad, disponibilidad y resistencia de los sistemas y servicios de procesamiento;<\/li>\n<li>Implementar medios para restaurar la disponibilidad y el acceso a los datos personales de forma oportuna en caso de incidente f\u00edsico o t\u00e9cnico;<\/li>\n<li>Garantizando el uso de un procedimiento para probar, analizar y evaluar peri\u00f3dicamente la eficacia de las medidas t\u00e9cnicas y organizativas para garantizar la seguridad del tratamiento.<\/li>\n<\/ul>\n<p><strong>7. COOKIES<\/strong><\/p>\n<p><strong>a. <\/strong><strong>Finalidad del uso de cookies<\/strong><\/p>\n<p>Como se ha explicado anteriormente, una cookie es un archivo de texto que se guarda autom\u00e1ticamente en el navegador de cualquier Usuario cuando visita un Sitio Web. Este archivo de texto puede contener datos personales y\/o informaci\u00f3n relativa a la navegaci\u00f3n del Usuario.<\/p>\n<p>La \u00fanica finalidad de las cookies utilizadas en el Sitio Web es mejorar tu experiencia de navegaci\u00f3n como Usuario. Las cookies utilizadas facilitan tu navegaci\u00f3n memorizando algunos de tus datos personales cuando accedes y navegas por el Sitio Web. En el Sitio Web se utilizan tres tipos de cookies, cuya finalidad var\u00eda en funci\u00f3n de su tipo:<\/p>\n<ul>\n<li><strong>Cookies funcionales<\/strong>: estas cookies permiten memorizar tus datos introducidos durante la autenticaci\u00f3n o las b\u00fasquedas realizadas en el Sitio Web;<\/li>\n<li><strong>Cookies publicitarias<\/strong>: estas cookies permiten identificar los h\u00e1bitos y preferencias de consumo y b\u00fasqueda de los Usuarios para ofrecerles contenidos publicitarios acordes con sus preferencias personales;<\/li>\n<li><strong>Cookies de seguridad<\/strong>: estas cookies permiten la seguridad de los datos personales de los Usuarios garantizando la encriptaci\u00f3n de los datos contenidos en otras cookies.<\/li>\n<\/ul>\n<p><strong>b. <\/strong><strong>Cookies utilizadas, vida \u00fatil y funci\u00f3n<\/strong><\/p>\n<p>Cada cookie utilizada en el Sitio Web es identificable por un nombre. Cada cookie tiene una vida \u00fatil, es decir, un periodo de tiempo tras el cual desaparece y deja de estar activa, olvidando los datos personales que almacenaba. Cada cookie tambi\u00e9n tiene una funci\u00f3n, o prop\u00f3sito, que justifica su colocaci\u00f3n en el Sitio Web.<\/p>\n<p>Aqu\u00ed tienes la lista de cookies utilizadas en el Sitio Web con su nombre, duraci\u00f3n, proveedor y funci\u00f3n:<\/p>\n<table width=\"556\">\n<tbody>\n<tr>\n<td width=\"139\"><strong>Nombre<\/strong><\/td>\n<td width=\"107\"><strong>Proveedor<\/strong><\/td>\n<td width=\"78\"><strong>Vida \u00fatil<\/strong><\/td>\n<td width=\"232\"><strong>Funci\u00f3n<\/strong><\/td>\n<\/tr>\n<tr>\n<td width=\"139\">CookieConsent<\/td>\n<td width=\"107\">bs-battery.com<\/td>\n<td width=\"78\">1 a\u00f1o<\/td>\n<td width=\"232\">Almacena el estado de consentimiento de cookies del usuario para el dominio actual<\/td>\n<\/tr>\n<tr>\n<td width=\"139\">wordpress_test_cookie<\/td>\n<td width=\"107\">bs-bater\u00eda.com<\/td>\n<td width=\"78\">Sesi\u00f3n<\/td>\n<td width=\"232\">Se utiliza para comprobar si el navegador del usuario admite cookies.<\/td>\n<\/tr>\n<tr>\n<td width=\"139\">wpEmojiSettingsSupports<\/td>\n<td width=\"107\">bs-battery.com<\/td>\n<td width=\"78\">Sesi\u00f3n<\/td>\n<td width=\"232\">Esta cookie forma parte de un conjunto de cookies que sirven para la entrega y presentaci\u00f3n de contenidos. Las cookies mantienen el estado correcto de la fuente, los deslizadores de blog\/im\u00e1genes, los temas de color y otros ajustes del sitio web.<\/td>\n<\/tr>\n<tr>\n<td width=\"139\">CONSENTIMIENTO<\/td>\n<td width=\"107\">youtube.com<\/td>\n<td width=\"78\">2 a\u00f1os<\/td>\n<td width=\"232\">Se utiliza para detectar si el visitante ha aceptado la categor\u00eda de marketing en el banner de cookies. Esta cookie es necesaria para el cumplimiento del GDPR por parte del sitio web.<\/td>\n<\/tr>\n<tr>\n<td width=\"139\">SID<\/td>\n<td width=\"107\">youtube.com<\/td>\n<td width=\"78\">Sesi\u00f3n<\/td>\n<td width=\"232\">Conserva los estados de los usuarios a trav\u00e9s de las peticiones de p\u00e1gina.<\/td>\n<\/tr>\n<tr>\n<td width=\"139\">METADATOS_DE_PRIVACIDAD_DEL_VISITANTE<\/td>\n<td width=\"107\">youtube.com<\/td>\n<td width=\"78\">180 d\u00edas<\/td>\n<td width=\"232\">Almacena el estado de consentimiento de cookies del usuario para el dominio actual<\/td>\n<\/tr>\n<tr>\n<td width=\"139\">td<\/td>\n<td width=\"107\">www.googletagmanager.com<\/td>\n<td width=\"78\">Sesi\u00f3n<\/td>\n<td width=\"232\">Registra datos estad\u00edsticos sobre el comportamiento de los usuarios en el sitio web. Utilizado para an\u00e1lisis internos por el operador del sitio web.<\/td>\n<\/tr>\n<tr>\n<td width=\"139\">_ga<\/td>\n<td width=\"107\">bs-battery.com<\/td>\n<td width=\"78\">2 a\u00f1os<\/td>\n<td width=\"232\">Se utiliza para enviar datos a Google Analytics sobre el dispositivo y el comportamiento del visitante. Realiza un seguimiento del visitante en todos los dispositivos y canales de marketing.<\/td>\n<\/tr>\n<tr>\n<td width=\"139\">_ga_#<\/td>\n<td width=\"107\">bs-battery.com<\/td>\n<td width=\"78\">2 a\u00f1os<\/td>\n<td width=\"232\">Se utiliza para enviar datos a Google Analytics sobre el dispositivo y el comportamiento del visitante. Realiza un seguimiento del visitante en todos los dispositivos y canales de marketing.<\/td>\n<\/tr>\n<tr>\n<td width=\"139\">_gat<\/td>\n<td width=\"107\">bs-battery.com<\/td>\n<td width=\"78\">1 d\u00eda<\/td>\n<td width=\"232\">Se utiliza para enviar datos a Google Analytics sobre el dispositivo y el comportamiento del visitante. Realiza un seguimiento del visitante en todos los dispositivos y canales de marketing.<\/td>\n<\/tr>\n<tr>\n<td width=\"139\">_gid<\/td>\n<td width=\"107\">bs-battery.com<\/td>\n<td width=\"78\">1 d\u00eda<\/td>\n<td width=\"232\">Se utiliza para enviar datos a Google Analytics sobre el dispositivo y el comportamiento del visitante. Realiza un seguimiento del visitante en todos los dispositivos y canales de marketing.<\/td>\n<\/tr>\n<tr>\n<td width=\"139\">__Seguro-1PAPISID<\/td>\n<td width=\"107\">youtube.com<\/td>\n<td width=\"78\">Sesi\u00f3n<\/td>\n<td width=\"232\">Registra un ID \u00fanico que Google utiliza para mantener estad\u00edsticas de c\u00f3mo el visitante utiliza los v\u00eddeos de YouTube en diferentes sitios web.<\/td>\n<\/tr>\n<tr>\n<td width=\"139\">__Secure-1PSID<\/td>\n<td width=\"107\">youtube.com<\/td>\n<td width=\"78\">Session<\/td>\n<td width=\"232\">Registers a unique ID that is used by Google to keep statistics of how the visitor uses YouTube videos across different websites.<\/p>\n<p>&nbsp;<\/p>\n<p>&nbsp;<\/td>\n<\/tr>\n<tr>\n<td width=\"139\">APISID<\/td>\n<td width=\"107\">youtube.com<\/td>\n<td width=\"78\">Sesi\u00f3n<\/td>\n<td width=\"232\">Registra un ID \u00fanico que Google utiliza para mantener estad\u00edsticas de c\u00f3mo el visitante utiliza los v\u00eddeos de YouTube en diferentes sitios web.<\/td>\n<\/tr>\n<tr>\n<td width=\"139\">HSID<\/td>\n<td width=\"107\">youtube.com<\/td>\n<td width=\"78\">Sesi\u00f3n<\/td>\n<td width=\"232\">Registra un ID \u00fanico que Google utiliza para mantener estad\u00edsticas de c\u00f3mo el visitante utiliza los v\u00eddeos de YouTube en diferentes sitios web.<\/td>\n<\/tr>\n<tr>\n<td width=\"139\">CLAVE_ENTRADA_\u00daLTIMO_RESULTADO<\/td>\n<td width=\"107\">youtube.com<\/td>\n<td width=\"78\">Sesi\u00f3n<\/td>\n<td width=\"232\">Se utiliza para rastrear la interacci\u00f3n del usuario con el contenido incrustado.<\/td>\n<\/tr>\n<tr>\n<td width=\"139\">LOGIN_INFO<\/td>\n<td width=\"107\">youtube.com<\/td>\n<td width=\"78\">Sesi\u00f3n<\/td>\n<td width=\"232\">Se utiliza para rastrear la interacci\u00f3n del usuario con el contenido incrustado.<\/td>\n<\/tr>\n<tr>\n<td width=\"139\">LogsDatabaseV2:V#||LogsRequestsStore<\/td>\n<td width=\"107\">youtube.com<\/td>\n<td width=\"78\">Persistente<\/td>\n<td width=\"232\">Se utiliza para rastrear la interacci\u00f3n del usuario con el contenido incrustado.<\/td>\n<\/tr>\n<tr>\n<td width=\"139\">siguienteId<\/td>\n<td width=\"107\">youtube.com<\/td>\n<td width=\"78\">Sesi\u00f3n<\/td>\n<td width=\"232\">Se utiliza para rastrear la interacci\u00f3n del usuario con el contenido incrustado.<\/td>\n<\/tr>\n<tr>\n<td width=\"139\">remote_sid<\/td>\n<td width=\"107\">youtube.com<\/td>\n<td width=\"78\">Sesi\u00f3n<\/td>\n<td width=\"232\">Necesaria para la implementaci\u00f3n y funcionalidad del contenido de v\u00eddeo de YouTube en el sitio web.<\/td>\n<\/tr>\n<tr>\n<td width=\"139\">solicita<\/td>\n<td width=\"107\">youtube.com<\/td>\n<td width=\"78\">Sesi\u00f3n<\/td>\n<td width=\"232\">Se utiliza para rastrear la interacci\u00f3n del usuario con el contenido incrustado.<\/td>\n<\/tr>\n<tr>\n<td width=\"139\">SAPISID<\/td>\n<td width=\"107\">youtube.com<\/td>\n<td width=\"78\">Sesi\u00f3n<\/td>\n<td width=\"232\">Se utiliza para rastrear la interacci\u00f3n del usuario con el contenido incrustado.<\/td>\n<\/tr>\n<tr>\n<td width=\"139\">ServicioTrabajadorLogsBaseDeDatos#SWHealthLog<\/td>\n<td width=\"107\">youtube.com<\/td>\n<td width=\"78\">Persistente<\/td>\n<td width=\"232\">Necesaria para la implementaci\u00f3n y funcionalidad del contenido de v\u00eddeo de YouTube en el sitio web.<\/td>\n<\/tr>\n<tr>\n<td width=\"139\">SSID<\/td>\n<td width=\"107\">youtube.com<\/td>\n<td width=\"78\">Sesi\u00f3n<\/td>\n<td width=\"232\">Registra un ID \u00fanico que Google utiliza para mantener estad\u00edsticas de c\u00f3mo el visitante utiliza los v\u00eddeos de YouTube en diferentes sitios web.<\/td>\n<\/tr>\n<tr>\n<td width=\"139\">TESTCOOKIESENABLED<\/td>\n<td width=\"107\">youtube.com<\/td>\n<td width=\"78\">1 d\u00eda<\/td>\n<td width=\"232\">Se utiliza para rastrear la interacci\u00f3n del usuario con el contenido incrustado.<\/td>\n<\/tr>\n<tr>\n<td width=\"139\">VISITANTE_INFO1_EN_VIVO<\/td>\n<td width=\"107\">youtube.com<\/td>\n<td width=\"78\">180 d\u00edas<\/td>\n<td width=\"232\">Utilizado para rastrear la interacci\u00f3n del usuario con el contenido incrustado.<\/td>\n<\/tr>\n<tr>\n<td width=\"139\">YSC<\/td>\n<td width=\"107\">youtube.com<\/td>\n<td width=\"78\">Sesi\u00f3n<\/td>\n<td width=\"232\">Se utiliza para rastrear la interacci\u00f3n del usuario con el contenido incrustado.<\/td>\n<\/tr>\n<tr>\n<td width=\"139\">yt.innertube::nextId<\/td>\n<td width=\"107\">youtube.com<\/td>\n<td width=\"78\">Persistente<\/td>\n<td width=\"232\">Registra un ID \u00fanico para mantener estad\u00edsticas de qu\u00e9 v\u00eddeos de YouTube ha visto el usuario.<\/td>\n<\/tr>\n<tr>\n<td width=\"139\">yt.innertube::solicitudes<\/td>\n<td width=\"107\">youtube.com<\/td>\n<td width=\"78\">Persistente<\/td>\n<td width=\"232\">Registra un ID \u00fanico para mantener estad\u00edsticas de qu\u00e9 v\u00eddeos de YouTube ha visto el usuario.<\/td>\n<\/tr>\n<tr>\n<td width=\"139\">ytidb::CLAVE_\u00daLTIMO_RESULTADO_ENTRADA<\/td>\n<td width=\"107\">youtube.com<\/td>\n<td width=\"78\">Persistente<\/td>\n<td width=\"232\">Se utiliza para rastrear la interacci\u00f3n del usuario con el contenido incrustado.<\/td>\n<\/tr>\n<tr>\n<td width=\"139\">YtIdbMeta#basesde datos<\/td>\n<td width=\"107\">youtube.com<\/td>\n<td width=\"78\">Persistente<\/td>\n<td width=\"232\">Se utiliza para rastrear la interacci\u00f3n del usuario con el contenido incrustado.<\/td>\n<\/tr>\n<tr>\n<td width=\"139\">yt-remote-cast-available<\/td>\n<td width=\"107\">youtube.com<\/td>\n<td width=\"78\">Sesi\u00f3n<\/td>\n<td width=\"232\">Almacena las preferencias del usuario sobre el reproductor de v\u00eddeo que utiliza el v\u00eddeo incrustado de YouTube<\/td>\n<\/tr>\n<tr>\n<td width=\"139\">yt-remote-cast-installed<\/td>\n<td width=\"107\">youtube.com<\/td>\n<td width=\"78\">Sesi\u00f3n<\/td>\n<td width=\"232\">Almacena las preferencias del usuario sobre el reproductor de v\u00eddeo que utiliza el v\u00eddeo incrustado de YouTube<\/td>\n<\/tr>\n<tr>\n<td width=\"139\">dispositivos conectados a distancia<\/td>\n<td width=\"107\">youtube.com<\/td>\n<td width=\"78\">Persistente<\/td>\n<td width=\"232\">Almacena las preferencias de reproducci\u00f3n de v\u00eddeo del usuario utilizando v\u00eddeo incrustado de YouTube<\/td>\n<\/tr>\n<tr>\n<td width=\"139\">yt-remote-device-id<\/td>\n<td width=\"107\">youtube.com<\/td>\n<td width=\"78\">Persistente<\/td>\n<td width=\"232\">Almacena las preferencias del reproductor de v\u00eddeo del usuario que utiliza el v\u00eddeo incrustado de YouTube<\/td>\n<\/tr>\n<tr>\n<td width=\"139\">yt-remote-fast-check-period<\/td>\n<td width=\"107\">youtube.com<\/td>\n<td width=\"78\">Sesi\u00f3n<\/td>\n<td width=\"232\">Almacena las preferencias del usuario sobre el reproductor de v\u00eddeo que utiliza el v\u00eddeo incrustado de YouTube<\/td>\n<\/tr>\n<tr>\n<td width=\"139\">yt-remote-session-app<\/td>\n<td width=\"107\">youtube.com<\/td>\n<td width=\"78\">Sesi\u00f3n<\/td>\n<td width=\"232\">Almacena las preferencias de reproducci\u00f3n de v\u00eddeo del usuario mediante un v\u00eddeo incrustado de YouTube<\/td>\n<\/tr>\n<tr>\n<td width=\"139\">nombre-sesi\u00f3n-yt-remota<\/td>\n<td width=\"107\">youtube.com<\/td>\n<td width=\"78\">Sesi\u00f3n<\/td>\n<td width=\"232\">Almacena las preferencias del usuario sobre el reproductor de v\u00eddeo que utiliza el v\u00eddeo incrustado de YouTube<\/td>\n<\/tr>\n<\/tbody>\n<\/table>\n<p>&nbsp;<\/p>\n<p><strong>c. Gesti\u00f3n de cookies: activaci\u00f3n y desactivaci\u00f3n <\/strong><\/p>\n<p>El Usuario tiene la posibilidad de gestionar las Cookies en el navegador que utilice en cada momento. El Usuario puede activarlas o desactivarlas en cualquier momento. Los medios de gesti\u00f3n de las Cookies dependen de cada navegador. Para facilitar la gesti\u00f3n de las cookies del Usuario, a continuaci\u00f3n se ofrece una ayuda explicativa para la gesti\u00f3n de las cookies en los principales navegadores utilizados por los Usuarios:<\/p>\n<ul>\n<li><strong>Google chrome: <\/strong>https:\/\/support.google.com\/accounts\/answer\/61416?co=GENIE.Platform%3DDesktop&amp;hl=fr<\/li>\n<li><strong>Safari : <\/strong>https:\/\/support.apple.com\/fr-fr\/guide\/safari\/sfri11471\/mac<\/li>\n<li><strong>Mozilla Firefox :<\/strong> https:\/\/support.mozilla.org\/fr\/kb\/activer-ou-desactiver-les-cookies on-firefox-for-android<\/li>\n<li><strong>Explorador de Internet : <\/strong>https:\/\/support.microsoft.com\/fr-fr\/help\/17442\/windows-internet-explorer-delete-manage-cookies<\/li>\n<\/ul>\n<h4><span style=\"color: #cd1719;\">8. DERECHOS DE LOS USUARIOS<\/span><\/h4>\n<ul>\n<li><strong>Acceso, rectificaci\u00f3n, supresi\u00f3n, oposici\u00f3n y restricci\u00f3n<\/strong><\/li>\n<\/ul>\n<p>El Usuario tiene derecho a solicitar al Responsable del Tratamiento el acceso a sus datos personales, su rectificaci\u00f3n o supresi\u00f3n, o la limitaci\u00f3n del tratamiento de los datos relativos al Usuario en cuesti\u00f3n, as\u00ed como a oponerse al tratamiento y el derecho a la portabilidad de los datos.<\/p>\n<ul>\n<li><strong>Retirada del consentimiento<\/strong><\/li>\n<\/ul>\n<p>Los Usuarios tienen derecho a retirar su consentimiento para el tratamiento de sus datos personales en cualquier momento. Esta retirada del consentimiento surtir\u00e1 efecto cuando el Responsable del Tratamiento reciba la notificaci\u00f3n de la retirada del consentimiento del Usuario.<\/p>\n<ul>\n<li><strong>Derecho a presentar una denuncia<\/strong><\/li>\n<\/ul>\n<p>El Usuario tiene derecho a presentar una reclamaci\u00f3n ante la Commission Nationale de l&#8217;Informatique et des Libert\u00e9s (CNIL) a trav\u00e9s del formulario de contacto disponible en el siguiente sitio web: https:\/\/www.cnil.fr\/fr;o ante la Direction G\u00e9n\u00e9rale de la Concurrence, de la Consommation et de la r\u00e9pression des fraudes a trav\u00e9s del formulario de contacto disponible en https:\/\/www.economie.gouv.fr\/dgccrf.<\/p>\n<p>El Usuario podr\u00e1 ejercer los derechos anteriormente expuestos en relaci\u00f3n con esta Pol\u00edtica notific\u00e1ndolo al Responsable del Tratamiento a la siguiente direcci\u00f3n de correo electr\u00f3nico: <a href=\"mailto:contact@bs-battery.com\">contact@bs-battery.com<\/a><\/p>\n<p><strong><em>MERCASAFE 2024<\/em><\/strong><em>\u00a9<\/em><em> &#8211; MS 1001-179048<\/em><\/p>\n<\/div><\/div><\/div><\/div><\/div><div class=\"w-tabs-section\" id=\"ce05\"><button aria-controls=\"content-ce05\" class=\"w-tabs-section-header\"><div class=\"w-tabs-section-title\">CONDICIONES DE USO<\/div><div class=\"w-tabs-section-control\"><\/div><\/button><div class=\"w-tabs-section-content\" id=\"content-ce05\" aria-expanded=\"false\"><div class=\"w-tabs-section-content-h i-cf\"><div class=\"wpb_text_column\"><div class=\"wpb_wrapper\"><p>Las presentes Condiciones de Uso (en adelante<strong>\u00abCDU<\/strong>\u00ab) son un contrato celebrado entre :<\/p>\n<p>Cualquier persona que navegue por el sitio web: <u>bs-battery.com<\/u>, (en adelante el<strong>\u00abUsuario<\/strong>\u00ab)<\/p>\n<p>Y<\/p>\n<p>COFINAS Sas, a company incorporated the laws of France with the registration number 30593368100069 and registered at the address: 30 RUE PASTEUR, 92150 SURESNES, FRANCE (hereinafter the \u00ab<strong>Editor<\/strong>\u00ab).<\/p>\n<h4><span style=\"color: #cd1719;\">1. PROP\u00d3SITO<\/span><\/h4>\n<ul>\n<li>1. Las presentes Condiciones de uso (en adelante, las<strong>\u00abCDU<\/strong>\u00ab) tienen por objeto definir las condiciones de uso de cualquier persona que navegue (en adelante, el \u00abUsuario\u00bb) por el Sitio web (en adelante, el<strong>\u00abSitio web<\/strong>\u00ab) del Editor. La finalidad del Sitio Web del Editor es la presentaci\u00f3n de la empresa del Editor y de sus productos.<\/li>\n<li>2. Excepcionalmente, el Editor podr\u00e1 aceptar la modificaci\u00f3n, adici\u00f3n o supresi\u00f3n de disposiciones de las presentes CDU mediante acuerdo por escrito. El Editor se reserva el derecho de modificar o actualizar las presentes CDU sin justificaci\u00f3n ni prejuicio, por lo que recomienda a los Usuarios que lean sistem\u00e1ticamente las CDU antes de cualquier nueva navegaci\u00f3n en el Sitio Web. La fecha de la \u00faltima actualizaci\u00f3n de las presentes CDU se muestra en negrita en la parte superior de esta p\u00e1gina.<\/li>\n<\/ul>\n<h4><span style=\"color: #cd1719;\">2. \u00c1MBITO DE APLICACI\u00d3N<\/span><\/h4>\n<p>Estas CDU se aplican a todos los Usuarios que visiten el Sitio Web. Al acceder al Sitio Web, el Usuario reconoce haber le\u00eddo y aceptado estas Condiciones de Uso, que establecen sus derechos y obligaciones en el contexto de su navegaci\u00f3n por el Sitio Web.<\/p>\n<h4><span style=\"color: #cd1719;\">3. P\u00c1GINA WEB<\/span><\/h4>\n<ul>\n<li><strong>1. <\/strong><strong>Accesibilidad<\/strong><\/li>\n<\/ul>\n<p>El Sitio Web del Editor se encuentra en la siguiente direcci\u00f3n: <u>bs-battery.com<\/u>. El acceso al Sitio Web es gratuito para todos los Usuarios con acceso a Internet, sin embargo, los costes en los que incurra el Usuario por la conexi\u00f3n y el uso de Internet no corren a cargo del Editor.<\/p>\n<p>Cada Usuario reconoce ser mayor de 16 a\u00f1os o estar acompa\u00f1ado por un tutor legal para navegar por el Sitio Web.<\/p>\n<ul>\n<li><strong>2. <\/strong><strong>Contenido<\/strong><\/li>\n<\/ul>\n<p>El Editor carga contenido en el Sitio Web y garantiza que realiza sus mejores esfuerzos para asegurar la exactitud y validez de la informaci\u00f3n en l\u00ednea en el Sitio Web. El Editor se reserva el derecho de modificar o actualizar el contenido sin justificaci\u00f3n, prejuicio o aviso.<\/p>\n<p>Es posible que el contenido del Sitio Web contenga informaci\u00f3n inexacta, incompleta o err\u00f3nea como resultado de un error t\u00e9cnico o involuntario por parte del Editor. El Editor se compromete a corregir estos errores de buena fe, lo antes posible, tan pronto como tenga conocimiento de ellos.<\/p>\n<h4><span style=\"color: #cd1719;\">4. DATOS PERSONALES Y COOKIES<\/span><\/h4>\n<p>El Editor se compromete a preservar la confidencialidad de los datos personales y de navegaci\u00f3n de los Usuarios. Los datos personales de los Usuarios pueden ser procesados por el Editor en particular para proceder a la creaci\u00f3n de una cuenta de cliente o a la presentaci\u00f3n de una solicitud de contacto en el Sitio web. Los datos de navegaci\u00f3n se utilizan para facilitar la navegaci\u00f3n del Usuario en el Sitio web.<\/p>\n<p>Si el Usuario da su consentimiento, sus datos personales y sus datos de navegaci\u00f3n podr\u00e1n ser procesados por el Editor. El Editor se compromete a garantizar el cumplimiento de las disposiciones del Reglamento General de Protecci\u00f3n de Datos 2017\/679 (GDPR) del Parlamento Europeo y del Consejo de fecha 14 de abril de 2016, garantizando el cumplimiento de los periodos de conservaci\u00f3n, la necesidad de recopilar los datos personales mencionados y la confidencialidad de los datos personales recopilados. Para m\u00e1s informaci\u00f3n, consulta nuestra Pol\u00edtica de Privacidad y Cookies disponible aqu\u00ed.<\/p>\n<h4><span style=\"color: #cd1719;\">5. ENLACES DE HIPERTEXTO<\/span><\/h4>\n<p>El Sitio Web del Editor puede contener enlaces de hipertexto que redirijan al Usuario a sitios de terceros. El Editor no es responsable de la p\u00e1gina a la que el enlace de hipertexto redirija a los Usuarios, ni del uso que pueda hacerse de dicho enlace. El Editor advierte a los Usuarios de los riesgos derivados de estos enlaces y recomienda a los Usuarios que utilicen estos enlaces de hipertexto con precauci\u00f3n.<\/p>\n<h4><span style=\"color: #cd1719;\">6. PROPIEDAD INTELECTUAL<\/span><\/h4>\n<p>Todos los elementos presentes en el Sitio Web del Editor est\u00e1n sujetos a derechos de propiedad intelectual reservados del Editor. Adem\u00e1s, el Sitio Web puede contener o redirigir a contenidos espec\u00edficos sujetos a derechos reservados de propiedad intelectual de terceros. Se proh\u00edbe cualquier reproducci\u00f3n, explotaci\u00f3n, redistribuci\u00f3n o uso, incluso parcial, de los elementos, incluidos los documentos legales y administrativos presentes en el Sitio Web del Editor o vinculados al mismo.<\/p>\n<h4><span style=\"color: #cd1719;\">7. RESPONSABILIDAD<\/span><\/h4>\n<p>El Editor se compromete a realizar sus mejores esfuerzos para garantizar el correcto funcionamiento, la seguridad y la accesibilidad del Sitio web. El Sitio Web se proporciona \u00abtal cual\u00bb y el Editor se compromete a proporcionar sus mejores esfuerzos para el correcto funcionamiento, seguridad y accesibilidad del Sitio Web. Sin embargo, el Editor no ser\u00e1 responsable ante el Usuario en caso de :<\/p>\n<ul>\n<li>mal funcionamiento, fallo de seguridad o indisponibilidad de determinados servicios del Sitio Web<\/li>\n<li>los da\u00f1os directos o indirectos resultantes de la informaci\u00f3n presente en el Sitio Web<\/li>\n<\/ul>\n<p>El Editor no ser\u00e1 responsable de ning\u00fan da\u00f1o causado al Usuario o a terceros como resultado de un Uso del Sitio web contrario a estas CDU por parte del Usuario. El Usuario ser\u00e1 el \u00fanico responsable del Uso que haga del Sitio web y se compromete a indemnizar y compensar al Editor en caso de da\u00f1os, p\u00e9rdidas o lucro cesante del Editor causados por el Usuario durante el uso del Sitio web.<\/p>\n<h4><span style=\"color: #cd1719;\">8. VIGILANCIA<\/span><\/h4>\n<p>Si una o m\u00e1s de las disposiciones de estas CDU se consideran inv\u00e1lidas en virtud de cualquier ley aplicable o de una decisi\u00f3n definitiva de un tribunal competente, las disposiciones no afectadas por esta invalidaci\u00f3n seguir\u00e1n siendo aplicables en su totalidad.<\/p>\n<h4><span style=\"color: #cd1719;\">9. LEY APLICABLE Y JURISDICCI\u00d3N<\/span><\/h4>\n<p>Las presentes CDU est\u00e1n sujetas a la legislaci\u00f3n francesa. En caso de litigio entre el Usuario y el Editor, las partes favorecer\u00e1n una resoluci\u00f3n amistosa del litigio. Cualquier litigio relativo a la interpretaci\u00f3n y\/o la ejecuci\u00f3n de las presentes CDU se someter\u00e1 a la jurisdicci\u00f3n de los tribunales de Par\u00eds, Francia.<\/p>\n<p><strong><em>MERCASAFE 202<\/em><\/strong><strong><em>4<\/em><\/strong><em>\u00a9 <\/em><em>&#8211; MS 1001-179048<\/em><\/p>\n<\/div><\/div><\/div><\/div><\/div><\/div><\/div><div class=\"w-separator size_huge\"><\/div><\/div><\/div><\/div><\/div><\/div><\/section>\n","protected":false},"excerpt":{"rendered":"CONDICIONES GENERALESHOMEP\u00e1ginasAVISO LEGALPOL\u00cdTICA DE PRIVACIDADCONDICIONES DE USOAVISO LEGALWelcome to the website bs-battery.com, a website operated by COFINAS Sas, a company incorporated the laws of France with the SIRET registration number 30593368100069 and registered at the address: 30 RUE PASTEUR, 92150 SURESNES, FRANCE. ADDITIONAL INFORMATION ABOUT COFINAS Sas: N\u00famero de registro de IVA: FR 53 305...","protected":false},"author":2,"featured_media":0,"parent":0,"menu_order":0,"comment_status":"closed","ping_status":"closed","template":"","meta":{"_acf_changed":false,"passster_activate_protection":false,"passster_protect_child_pages":"","passster_protection_type":"password","passster_password":"","passster_passwords":"","passster_password_list":"","passster_password_lists":"","passster_activate_user_restriction":"","passster_user_restriction_type":"user-role","passster_user_restriction":"no-role","passster_activate_overwrite_defaults":"","passster_headline":"","passster_instruction":"","passster_placeholder":"","passster_button":"","passster_id":"","passster_activate_misc_settings":"","passster_redirect_url":"","passster_hide":"no","passster_area_shortcode":"","_monsterinsights_skip_tracking":false,"_monsterinsights_sitenote_active":false,"_monsterinsights_sitenote_note":"","_monsterinsights_sitenote_category":0,"_uf_show_specific_survey":0,"_uf_disable_surveys":false,"footnotes":""},"class_list":["post-35203","page","type-page","status-publish","hentry"],"acf":[],"aioseo_notices":[],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v27.9 - https:\/\/yoast.com\/product\/yoast-seo-wordpress\/ -->\n<title>CONDICIONES GENERALES - BS BATTERY<\/title>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/bs-battery.com\/es\/condiciones-generales\/\" \/>\n<meta property=\"og:locale\" content=\"es_ES\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"CONDICIONES GENERALES - BS BATTERY\" \/>\n<meta property=\"og:url\" content=\"https:\/\/bs-battery.com\/es\/condiciones-generales\/\" \/>\n<meta property=\"og:site_name\" content=\"BS BATTERY\" \/>\n<meta property=\"article:modified_time\" content=\"2026-03-30T06:53:21+00:00\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:label1\" content=\"Tiempo de lectura\" \/>\n\t<meta name=\"twitter:data1\" content=\"19 minutos\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/bs-battery.com\\\/es\\\/condiciones-generales\\\/\",\"url\":\"https:\\\/\\\/bs-battery.com\\\/es\\\/condiciones-generales\\\/\",\"name\":\"CONDICIONES GENERALES - BS BATTERY\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/bs-battery.com\\\/#website\"},\"datePublished\":\"2025-03-11T16:16:29+00:00\",\"dateModified\":\"2026-03-30T06:53:21+00:00\",\"breadcrumb\":{\"@id\":\"https:\\\/\\\/bs-battery.com\\\/es\\\/condiciones-generales\\\/#breadcrumb\"},\"inLanguage\":\"es\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/bs-battery.com\\\/es\\\/condiciones-generales\\\/\"]}]},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/bs-battery.com\\\/es\\\/condiciones-generales\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Home\",\"item\":\"https:\\\/\\\/bs-battery.com\\\/es\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"CONDICIONES GENERALES\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/bs-battery.com\\\/#website\",\"url\":\"https:\\\/\\\/bs-battery.com\\\/\",\"name\":\"BS BATTERY\",\"description\":\"The Power you need...\",\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/bs-battery.com\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"es\"}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"CONDICIONES GENERALES - BS BATTERY","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/bs-battery.com\/es\/condiciones-generales\/","og_locale":"es_ES","og_type":"article","og_title":"CONDICIONES GENERALES - BS BATTERY","og_url":"https:\/\/bs-battery.com\/es\/condiciones-generales\/","og_site_name":"BS BATTERY","article_modified_time":"2026-03-30T06:53:21+00:00","twitter_card":"summary_large_image","twitter_misc":{"Tiempo de lectura":"19 minutos"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"WebPage","@id":"https:\/\/bs-battery.com\/es\/condiciones-generales\/","url":"https:\/\/bs-battery.com\/es\/condiciones-generales\/","name":"CONDICIONES GENERALES - BS BATTERY","isPartOf":{"@id":"https:\/\/bs-battery.com\/#website"},"datePublished":"2025-03-11T16:16:29+00:00","dateModified":"2026-03-30T06:53:21+00:00","breadcrumb":{"@id":"https:\/\/bs-battery.com\/es\/condiciones-generales\/#breadcrumb"},"inLanguage":"es","potentialAction":[{"@type":"ReadAction","target":["https:\/\/bs-battery.com\/es\/condiciones-generales\/"]}]},{"@type":"BreadcrumbList","@id":"https:\/\/bs-battery.com\/es\/condiciones-generales\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Home","item":"https:\/\/bs-battery.com\/es\/"},{"@type":"ListItem","position":2,"name":"CONDICIONES GENERALES"}]},{"@type":"WebSite","@id":"https:\/\/bs-battery.com\/#website","url":"https:\/\/bs-battery.com\/","name":"BS BATTERY","description":"The Power you need...","potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/bs-battery.com\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"es"}]}},"_links":{"self":[{"href":"https:\/\/bs-battery.com\/es\/wp-json\/wp\/v2\/pages\/35203","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/bs-battery.com\/es\/wp-json\/wp\/v2\/pages"}],"about":[{"href":"https:\/\/bs-battery.com\/es\/wp-json\/wp\/v2\/types\/page"}],"author":[{"embeddable":true,"href":"https:\/\/bs-battery.com\/es\/wp-json\/wp\/v2\/users\/2"}],"replies":[{"embeddable":true,"href":"https:\/\/bs-battery.com\/es\/wp-json\/wp\/v2\/comments?post=35203"}],"version-history":[{"count":5,"href":"https:\/\/bs-battery.com\/es\/wp-json\/wp\/v2\/pages\/35203\/revisions"}],"predecessor-version":[{"id":44167,"href":"https:\/\/bs-battery.com\/es\/wp-json\/wp\/v2\/pages\/35203\/revisions\/44167"}],"wp:attachment":[{"href":"https:\/\/bs-battery.com\/es\/wp-json\/wp\/v2\/media?parent=35203"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}